{"id":6482,"date":"2019-12-18T21:45:47","date_gmt":"2019-12-18T20:45:47","guid":{"rendered":"https:\/\/www.realestate.it\/policy-gestione-conflitti-di-interesse\/"},"modified":"2019-12-18T21:45:47","modified_gmt":"2019-12-18T20:45:47","slug":"policy-gestione-conflitti-di-interesse","status":"publish","type":"page","link":"https:\/\/www.realestate.it\/de\/policy-gestione-conflitti-di-interesse\/","title":{"rendered":"Policy di gestione dei conflitti di interesse nella prestazione dei servizi e delle attivit\u00e0 di investimento"},"content":{"rendered":"<p>Policy di gestione dei conflitti di interesse nella prestazione dei servizi e delle attivit\u00e0 di investimento<\/p>\n<div class=\"table-1\">\n<table width=\"100%\">\n<thead>\n<tr>\n<th align=\"left\">ID documento:<\/th>\n<th align=\"left\">Policy conflitti di interesse<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<td align=\"left\">Versione:<\/td>\n<td align=\"left\">1.0<\/td>\n<\/tr>\n<tr>\n<td align=\"left\">Data:<\/td>\n<td align=\"left\">18\/12\/2019<\/td>\n<\/tr>\n<tr>\n<td align=\"left\">Autore:<\/td>\n<td align=\"left\">Thomas Moroder<\/td>\n<\/tr>\n<tr>\n<td align=\"left\">Approvato da:<\/td>\n<td align=\"left\">Amministratori<\/td>\n<\/tr>\n<tr>\n<td align=\"left\">Riservatezza:<\/td>\n<td align=\"left\">Documento pubblico<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<p>DEFINIZIONI<\/p>\n<div class=\"table-1\">\n<table width=\"100%\">\n<thead>\n<tr>\n<th align=\"left\">Gestore:<\/th>\n<th align=\"left\">REAL ESTATE INFORMATION TECHNOLOGY Srl, in forma abbreviata<br \/>\nREALESTATE.IT Srl<br \/>\nsede legale ed amministrativa: Laion (BZ), S. Pietro zona artig. Pontives 17 , 39040<br \/>\nC.F., n. iscr. al Registro Imprese e P.IVA: 03056170214<br \/>\nREA: BZ &#8211; 228207<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<td align=\"left\">MiFID<\/td>\n<td align=\"left\">Markets in Financial Instruments Directive (Direttiva 2004\/39\/CE)<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<p>PREMESSA<\/p>\n<p>Il Regolamento sulla raccolta di capitali tramite portali on-line adottato con delibera n. 18592 del 26 giugno 2013 e successive modifiche richiede ai gestori di portali elaborare, attuare e mantenere e un\u2019efficace politica sui conflitti di interesse, formulata per iscritto, che consenta di individuare le circostanze che generano o potrebbero generare un conflitto di interesse lesivo di uno pi\u00f9 investitori, e che definisca le procedure da seguire e le misure da adottare per prevenire o gestire tali conflitti.<\/p>\n<p>Solo quando le procedure e le misure elaborate non siano sufficienti per assicurare, con ragionevole certezza, che il rischio di nuocere agli interessi degli investitori sia evitato, il gestore, come misura estrema, comunica chiaramente agli stessi la natura generale e\/o le fonti di tali conflitti e le misure adottate per mitigare i relativi rischi (disclosure). L\u2019eccessivo ricorso da parte del gestore a tali comunicazioni agli investitori \u00e8 da considerarsi una carenza della politica sui conflitti di interesse.<\/p>\n<p>Il gestore valuta e riesamina periodicamente, almeno una volta all\u2019anno, la politica sui conflitti di interesse elaborata e adotta misure adeguate per rimediare ad eventuali carenze.<\/p>\n<p>CONTENUTI E SCOPO DEL DOCUMENTO<\/p>\n<p>Attraverso il presente documento, redatto in esecuzione dell\u2019art. 13 titolo III Regole di condotta del Regolamento sulla raccolta di capitali tramite portali on-line, il gestore persegue lo scopo di:<\/p>\n<ol>\n<li>identificare i conflitti di interesse che potrebbero sorgere, al momento della prestazione dei servizi di investimento e\/o accessori, tra il gestore, anche tramite i suoi soggetti rilevanti, ed i propri clienti nonch\u00e9 tra i clienti stessi;<\/li>\n<li>fornire indirizzi per la gestione dei conflitti di interesse anche con l\u2019adozione di idonee misure organizzative e assicurando che l\u2019affidamento di pi\u00f9 funzioni ai soggetti rilevanti del gestore, impegnati in attivit\u00e0 che implicano un conflitto di interesse, non impedisca loro di agire in modo indipendente, cos\u00ec da evitare che i conflitti medesimi incidano negativamente sugli interessi dei clienti;<\/li>\n<li>predisporre una corretta informazione ai clienti (disclosure) nel caso in cui le misure adottate non siano sufficienti ad evitare il rischio di nuocere agli interessi dei clienti medesimi.<\/li>\n<\/ol>\n<p>Ciascuna procedura o regola di condotta, relativa all\u2019erogazione di servizi e di attivit\u00e0 di investimento e accessori, viene adottata e mantenuta nel rispetto dei principi e delle regole fissati dal legislatore comunitario e nazionale. Le fattispecie di conflitti di interesse prese in esame nel presente documento non contemplano quei casi che realizzano di per s\u00e9 degli illeciti.<\/p>\n<p>RELAZIONE CON ALTRE NORME E DOCUMENTI<\/p>\n<p>I principi e le procedure descritti nella presente Policy vanno letti in stretta connessione con i seguenti atti di normativa interna adottati dal gestore:<\/p>\n<ul>\n<li>Policy operazioni personali dei soggetti rilevanti \u2013 Norme di comportamento<\/li>\n<li>Regolamento per la prevenzione e la gestione degli abusi di mercato<\/li>\n<li>Codice di comportamento in materia di Internal Dealing<\/li>\n<li>Execution &amp; transmission policy<\/li>\n<li>Policy aziendale in tema di incentivi nella prestazione dei servizi e delle attivit\u00e0 di investimento<\/li>\n<li>Codice Etico<\/li>\n<li>Politiche di remunerazione<\/li>\n<\/ul>\n<p>Le disposizioni contenute nei sopra elencati atti di normativa interna nonch\u00e9, ovviamente, nel presente documento devono:<\/p>\n<ul>\n<li>considerarsi prevalenti nel caso in cui anche una sola delle indicazioni ivi contenute dovesse entrare in conflitto con disposizioni previste in altre procedure o regolamenti interni<\/li>\n<li>ritenersi comunque un riferimento adeguato ad impostare sempre una corretta condotta operativa nell\u2019erogazione dei servizi d\u2019investimento, anche in assenza di puntuali procedure interne.<\/li>\n<\/ul>\n<p>Al fine di assicurare a tutti i destinatari la conoscenza dei principi, degli indirizzi e delle procedure adottati dal gestore, i documenti di cui sopra vengono recepiti ed ufficializzati secondo il modo d\u2019uso mediante disposizioni di servizio e\/o pubblicazione sul sito aziendale.<\/p>\n<p>SOGGETTI RILEVANTI<\/p>\n<p>Ai fini dell\u2019identificazione dei conflitti di interesse nella prestazione dei servizi e delle attivit\u00e0 di investimento, si considerano soggetti rilevanti in REALESTATE.IT Srl:<\/p>\n<ul>\n<li>i componenti del Consiglio di Amministrazione e\/o dell&#8217;amministrazione pluripersonale individuale disgiuntiva (dell&#8217;organo amministrativo)<\/li>\n<li>i membri del comitato rischi, valutazione appropriatezza ed advisory board<\/li>\n<\/ul>\n<p>nonch\u00e9<\/p>\n<ul>\n<li>i collaboratori del gestore che, in virt\u00f9 della funzione\/mansione svolta, prendano parte, direttamente o indirettamente, alla prestazione di servizi di investimento e all\u2019esercizio di attivit\u00e0 di investimento da parte del medesimo intermediario e che, pertanto<br \/>\n\u2022 siano coinvolti in attivit\u00e0 che possono dare origine a conflitti di interesse;<br \/>\n\u2022 abbiano accesso ad informazioni privilegiate;<br \/>\n\u2022 abbiano accesso ad informazioni confidenziali riguardanti clienti od operazioni con o per conto di clienti.<\/li>\n<\/ul>\n<p>IDENTIFICAZIONE DELLE TIPOLOGIE DI CONFLITTO DI INTERESSE RILEVANTI<\/p>\n<p>Al fine di individuare i conflitti di interesse potenzialmente insiti nell\u2019attivit\u00e0 di intermediazione finanziaria svolta dal gestore, \u00e8 stata effettuata una dettagliata mappatura che ha permesso di identificare tutte le ipotesi in cui l\u2019interesse dell\u2019investitore potrebbe risultare sacrificato.<\/p>\n<p>Le caratteristiche che deve possedere il conflitto per assumere rilievo sono:<\/p>\n<ul>\n<li>il carattere potenziale del conflitto stesso, che dovr\u00e0 pertanto essere apprezzabile ex ante<\/li>\n<li>l\u2019esistenza di una possibile subordinazione dell\u2019interesse del cliente rispetto a quello del gestore e\/o a quello di un altro cliente<\/li>\n<li>la sussistenza di una finalit\u00e0, diversa e ulteriore rispetto a quella propria dell\u2019operazione posta in essere, perseguita dal gestore al fine di trarne utilit\u00e0.<\/li>\n<\/ul>\n<p>Al fine di pervenire ad una esaustiva identificazione dei conflitti, si \u00e8 tenuto conto se il gestore, un soggetto rilevante o un soggetto ad essi riconducibile:<\/p>\n<ul>\n<li>possano realizzare un guadagno finanziario o evitare una perdita finanziaria, a danno del cliente<\/li>\n<li>siano portatori di un interesse nel risultato del servizio prestato al cliente, distinto e\/o ulteriore da quello del cliente medesimo<\/li>\n<li>abbiano un incentivo a privilegiare gli interessi di clienti diversi da quello a cui il servizio \u00e8 prestato<\/li>\n<li>svolgano la medesima attivit\u00e0 del cliente<\/li>\n<li>ricevano o possano ricevere da una persona diversa dal cliente, in relazione con il servizio a questi prestato, un incentivo, sotto forma di denaro, beni o servizi, diverso dalle commissioni o dalle competenze normalmente percepite per tale servizio.<\/li>\n<\/ul>\n<p>Sono invece sottratti alla disciplina dei conflitti di interesse:<\/p>\n<ul>\n<li>gli incentivi ricevuti\/pagati dalle\/alle imprese di investimento in quanto tali fattispecie vengono regolate nella Politica aziendale in tema di incentivi nella prestazione dei servizi e delle attivit\u00e0 di investimento, ai sensi dell\u2019art. 26 della Direttiva 2006\/73\/CE e della relativa normativa nazionale di recepimento (TUF e Regolamenti Consob e Banca d\u2019Italia).<\/li>\n<\/ul>\n<p>Conflitti di interesse connessi ai singoli servizi di investimento e accessori<\/p>\n<p>La mappatura delle ipotesi di conflitto effettuata dal gestore ha, in principio, individuato dei parametri che, combinati tra loro, possono dar luogo ad una situazione di potenziale conflitto che, seppur non ancora idonea a generare un pregiudizio per il cliente, va tuttavia individuata e monitorata per consentirne, in futuro, la corretta gestione.<\/p>\n<p>Tali parametri sono:<\/p>\n<ul>\n<li>tipologia del servizio (principale o accessorio) di investimento prestato<\/li>\n<li>unit\u00e0 organizzativa a cui \u00e8 attribuita la responsabilit\u00e0 nell\u2019erogazione del servizio prestato (process owner)<\/li>\n<li>tipologia dello strumento finanziario oggetto del servizio<\/li>\n<\/ul>\n<p>Le tipologie di servizi e di attivit\u00e0 di investimento rilevanti ai fini del presente documento prestati in REALESTATE.IT Srl sono:<br \/>\n&#8211; Ricezione e trasmissione di ordini<br \/>\n&#8211; Negoziazione per conto proprio<br \/>\n&#8211; Collocamento con o senza assunzione a fermo e\/o a garanzia nei confronti dell\u2019emittente<br \/>\n&#8211; Consulenza in materia di investimenti<br \/>\n&#8211; Custodia e amministrazione degli strumenti finanziari<br \/>\n&#8211; Ricerca in materia di investimenti, analisi finanziaria o altre forme di raccomandazione generale riguardanti operazioni relative a strumenti finanziari<\/p>\n<p>Sulla base dell\u2019organigramma in vigore dal 25 ottobre 2019, le unit\u00e0 organizzative responsabili in REALESTATE.IT Srl dell\u2019erogazione dei singoli servizi di investimento sono:<br \/>\n&#8211; Servizio Real Estate Equity Crowdfunding (REECF)<br \/>\n&#8211; Servizio Real Estate Lending Crowdfunding (RELCF)<\/p>\n<p>Le tipologie di strumenti finanziari oggetto dei servizi e delle attivit\u00e0 considerati sono:<br \/>\n&#8211; Strumenti finanziari collocati dal gestore<br \/>\n&#8211; Strumenti finanziari emessi da soggetti terzi nei confronti dei quali il gestore presenta interessi di varia natura (p. es., a mero titolo esemplificativo e non esaustivo: interesse a sviluppare affari o rapporti commerciali, interesse a variare la propria posizione creditizia, possesso di informazioni confidenziali, ecc.)<\/p>\n<p>In quest\u2019ultimo caso \u00e8 necessario per il gestore monitorare le emissioni di strumenti finanziari da parte di:<br \/>\n&#8211; Imprese affidate dal gestore;<br \/>\n&#8211; Fornitori strategici del gestore;<br \/>\n&#8211; Imprese cui sono prestati i servizi di consulenza in materia di struttura finanziaria ed eventuale assistenza all\u2019emissione e al collocamento;<br \/>\n&#8211; Societ\u00e0 con cui il gestore ha interesse a sviluppare rapporti di affari (banche, SGR, SICAV etc. )<\/p>\n<p>GESTIONE E MITIGAZIONE DEI CONFLITTI DI INTERESSE<br \/>\nMisure organizzative<\/p>\n<p>Le soluzioni organizzative individuate sono volte a garantire che i soggetti rilevanti, impegnati in attivit\u00e0 in conflitto, agiscano con un grado di indipendenza appropriato avuto riguardo alle dimensioni ed alla complessit\u00e0 operativa del gestore (principio di proporzionalit\u00e0), anche qualora l\u2019erogazione dei sopra menzionati servizi sia svolta in abbinamento; in tale ultimo caso sono predisposte adeguate procedure di gestione del conflitto a presidio della correttezza dell\u2019operativit\u00e0 cos\u00ec posta in essere.<\/p>\n<p>Le misure organizzative a presido, consistono, in particolare, nella ripartizione strutturale operativa delle responsabilit\u00e0 di svolgimento dei servizi (principali ed accessori) in capo a differenti unit\u00e0 organizzative, come si rinviene, in dettaglio, nel business model del gestore tempo per tempo vigente. Si segnala, inoltre, ai fini della presente, che:<\/p>\n<p>&#8211; il servizio accessorio di custodia, intestazione fiduciaria e rubricazione di strumenti finanziari della clientela \u00e8 materialmente svolto da DIRECTA S.I.M. p.A., terza ed esterna a REALESTATE.IT Srl;<br \/>\n&#8211; il servizio di ricerca e analisi in materia di investimenti, invece non viene prestato; in relazione a tale servizio accessorio, REALESTATE.IT Srl si limita alla divulgazione e messa a disposizione della clientela di materiale formato elaborato da analisti terzi.<\/p>\n<p>Si rileva, inoltre, come il gestore attualmente non faccia parte di alcun gruppo bancario o assicurativo n\u00e9 detenga partecipazioni rilevanti in societ\u00e0 attive nel campo dell\u2019intermediazione finanziaria.<br \/>\nTale circostanza fa s\u00ec che siano di fatto assenti tutte le problematiche connesse alle strutture del gruppo e\/o di partecipazione nella prestazione dei servizi di investimento.<\/p>\n<p>Misure operative generali<\/p>\n<p>Le misure operative messe in atto dal gestore per la gestione dei conflitti di interesse si possono riassumere come segue:<br \/>\n&#8211; adozione di un codice etico comprendente principi generali e norme comportamentali alle quali i membri del Consiglio di Amministrazione e\/o dell&#8217;amministrazione pluripersonale individuale disgiuntiva (dell&#8217;organo amministrativo), del comitato rischi, valutazione appropriatezza ed advisory board nonch\u00e9 tutti i collaboratori del gestore sono tenuti ad attenersi. Vige il principio che gli interessi dei clienti sono preminenti rispetto a quelli<br \/>\ndel gestore e dei suoi collaboratori.<br \/>\n&#8211; adozione di norme specifiche che regolano modalit\u00e0, condizioni e limiti allo svolgimento delle operazioni finanziarie personali di tutti i collaboratori del gestore con differenziato rigore (Policy operazioni personali dei soggetti rilevanti &#8211; norme di comportamento) con riguardo all&#8217;operativit\u00e0 in strumenti finanziari. Vige il principio che nell\u2019attivit\u00e0 di intermediazione in strumenti finanziari il gestore eviti comportamenti che possano avvantaggiare un cliente rispetto ad un altro.<br \/>\n&#8211; adozione di norme comportamentali concernenti le operazioni rilevanti ai fini del Codice di comportamento in materia di Internal Dealing.<br \/>\n&#8211; adozione di norme generali concernenti il comportamento da tenere in ordine alla riservatezza su notizie rilevanti di cui si sia venuti a qualsiasi titolo in possesso e all\u2019obbligo di evitare azioni configuranti abusi di mercato.<br \/>\n&#8211; adozione di norme generali concernenti il comportamento da tenere nei rapporti con i clienti, in particolare per quanto concerne la corresponsione o il ricevimentodi piccole attenzioni che non costituisce conflitto di interessi allorquando il valore delle stesse sia inferiore alla soglia stabilita nel Codice Etico di REALESTATE.IT Srl (EUR 50,00).<br \/>\n&#8211; istituzione della funzione di conformit\u00e0 (compliance) che con carattere di permanenza, efficacia ed indipendenza ha l\u2019incarico di istituire, applicare e mantenere politiche e procedure adeguate per individuare e minimizzare il rischio di mancata osservanza degli obblighi stabiliti dalla direttiva in tema di conflitti di interesse.<br \/>\n&#8211; predisposizione dell\u2019apposito registro dei conflitti di interesse (cfr. il successivo paragrafo).<\/p>\n<p>Misure operative specifiche<\/p>\n<p>Predisposizione di procedure per<br \/>\n&#8211; impedire o controllare lo scambio di informazioni tra i responsabili e i dipendenti dei servizi di cui al precedente punto, in qualit\u00e0 di soggetti rilevanti, impegnati in attivit\u00e0 che comportino un rischio di conflitto di interesse, quando lo scambio di tali informazioni possa ledere gli interessi di uno o pi\u00f9 clienti. Strumentale a tal fine \u00e8 la predisposizione, in seno a ciascun servizio, di appositi mansionari;<br \/>\n&#8211; la vigilanza separata di tali soggetti rilevanti le cui principali funzioni implicano l\u2019esercizio di attivit\u00e0 per conto dei clienti o la prestazione di servizi ai clienti i cui interessi potrebbero risultare in conflitto;<br \/>\n&#8211; la gestione delle informazioni privilegiate al fine di evitare condotte illecite ai sensi della normativa sul Market Abuse;<br \/>\n&#8211; procedure organizzative ed informatiche per garantire la corretta erogazione dei servizi di investimento e accessori, nel rispetto dell\u2019interesse del cliente;<br \/>\n&#8211; procedure per l\u2019esecuzione degli ordini che garantiscono al cliente il rispetto di precise regole, vietando ogni discrezionalit\u00e0 nella fase di esecuzione delle disposizioni impartite dallo stesso;<br \/>\n&#8211; l\u2019impedimento o la limitazione, da parte di qualsiasi persona, dell\u2019esercizio di un\u2019influenza indebita sullo svolgimento dei servizi o delle attivit\u00e0 di investimento o servizi accessori da parte di un soggetto rilevante;<br \/>\n&#8211; l\u2019impedimento o il controllo della partecipazione simultanea o consecutiva di tali soggetti rilevanti ai servizi di investimento quando questa possa nuocere alla gestione corretta dei conflitti di interesse;<br \/>\n&#8211; istituzione dell\u2019obbligo in capo ai responsabili dei singoli servizi di investimento di analizzare tutte le future convenzioni di collocamento di strumenti finanziari allo scopo di individuare possibili conflitti di interesse nocivi per i clienti, e di inviare i risultati di tali valutazioni alla funzione di conformit\u00e0 per la validazione;<br \/>\n&#8211; valutazione da parte della funzione di conformit\u00e0 di tutte le forme indirette di pagamento, monetarie e non (ad esempio inviti a viaggi premio o attenzioni varie), da parte delle societ\u00e0 prodotto delle quali il gestore colloca gli strumenti finanziari (altri gestori, sviluppatori immobiliari, altre societ\u00e0, eventualmente fondi e\/o SICAV);<br \/>\n&#8211; predisposizione delle misure di disclosure (informativa) ai clienti &#8211; al momento dell\u2019operazione e su supporto duraturo &#8211; in tutti i casi in cui i conflitti di interesse non sono eliminabili, come nel caso di:<br \/>\ni. collocamento di titoli obbligazionari (ordinari e convertibili) o di debito di propria emissione;<br \/>\nii. negoziazione in conto proprio di titoli obbligazionari o di debito di propria emissione;<br \/>\niii. collocamento di quote o titoli azionari di propria emissione, in occasione di aumenti di capitale sociale o di offerte pubbliche di vendita;<br \/>\niv. ricezione e trasmissione di ordini relativi a titoli azionari o quote di propria emissione;<br \/>\nv. ricezione e trasmissione di ordini relativi a diritti di opzione su titoli di propria emissione;<br \/>\nvi. consulenza su singoli strumenti finanziari, con contemporanea prestazione di altro servizio di investimento avente ad oggetto titoli o diritti\/opzioni su titoli emessi dal gestore e\/o da terzi;<br \/>\nvii. collocamenti di parti di Organismi di Investimento Collettivi di Risparmio (Fondi, Sicav) che prevedano commissioni di investimento differenziate tra prodotti similari;<br \/>\nviii. collocamenti di parti di Organismi di Investimento Collettivi di Risparmio (Fondi, Sicav) che prevedano la retrocessione al gestore di commissioni di gestione;<br \/>\nix. collocamento di strumenti finanziari (ivi compresi parti di OICR e prodotti finanziari emessi da imprese di assicurazioni ex art. 1 comma 1, lett. w-bis del TUF) emessi da soggetti terzi finanziati\/partecipati in misura rilevante<br \/>\ndal gestore o da soggetti con i quali il gestore intrattiene rapporti d\u2019affari.<\/p>\n<p>REGISTRO DEI CONFLITTI DI INTERESSE<\/p>\n<p>L\u2019art. 23 della Direttiva 2006\/73\/CE prescrive alle imprese di investimento di tenere e di aggiornare regolarmente un registro nel quale riportare i tipi di servizi di investimento o accessori o di attivit\u00e0 di investimento svolti, per i quali sia sorto o possa sorgere un conflitto di interesse che rischia di ledere gravemente gli interessi dei clienti.<\/p>\n<p>Scopo di tale registro \u00e8 recare la casistica anche su base storica, a partire dalla sua istituzione, dei servizi e delle attivit\u00e0 che possano originare o che abbiano originato insanabili conflitti di interesse.<\/p>\n<p>La Real Estate Information Technology S.r.l. ha istituito tale registro e affidato la relativa tenuta alla funzione di Compliance.<\/p>\n<p>INFORMATIVA SUI CONFLITTI DI INTERESSE<\/p>\n<p>Ai sensi dell\u2019art. 30 della Direttiva, la Real Estate Information Technology S.r.l. fornisce a tutti i clienti, al momento della formalizzazione contrattuale della prestazione dei servizi di investimento, una versione sintetica della presente politica di gestione dei conflitti di interesse; tale ultimo documento non costituisce, tuttavia, un\u2019autorizzazione a procedere bens\u00ec una comunicazione preventiva di cui il cliente deve tenere conto per decidere consapevolmente.<br \/>\nA richiesta dei clienti verr\u00e0 in ogni caso consegnata copia integrale del presente documento che \u00e8 altres\u00ec pubblicato sul sito internet del gestore.<\/p>\n<p>APPROVAZIONE E AGGIORNAMENTO DELLA POLITICA<\/p>\n<p>La politica di gestione dei conflitti di interesse, di cui al presente documento, \u00e8 stata creata ed approvata dal Consiglio di Amministrazione della Real Estate Information Technology S.r.l. nella sua riunione del 18 dicembre 2019.<\/p>\n<p>Al fine di mantenere un\u2019efficace politica di gestione dei conflitti di interesse, il gestore sottoporr\u00e0 a verifiche l&#8217;intero contenuto del presente documento di norma annualmente e ogni qualvolta si verifichi un cambiamento rilevante nell&#8217;operativit\u00e0 del gestore stesso.<\/p>\n<p>Il presente documento sar\u00e0 nel tempo aggiornato ad opera della funzione di Compliance al variare delle fattispecie di conflitto di interesse, ovvero di circostanze in grado di inficiare l\u2019efficacia delle misure adottate a tutela degli interessi dei clienti. Pertanto, il gestore si riserva il diritto di modificare e ampliare il presente documento, dandone opportuna comunicazione alla clientela e pubblicandone altres\u00ec una copia sul proprio sito aziendale.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Policy di gestione dei conflitti di interesse nella prestazione dei servizi e delle attivit\u00e0 di investimento ID documento: Policy conflitti di interesse Versione: 1.0 Data: 18\/12\/2019 Autore: Thomas Moroder Approvato da: Amministratori Riservatezza: Documento pubblico DEFINIZIONI Gestore: REAL ESTATE INFORMATION TECHNOLOGY Srl, in forma abbreviata REALESTATE.IT Srl sede legale ed amministrativa: Laion (BZ), S. Pietro &#8230; <a title=\"Policy di gestione dei conflitti di interesse nella prestazione dei servizi e delle attivit\u00e0 di investimento\" class=\"read-more\" href=\"https:\/\/www.realestate.it\/de\/policy-gestione-conflitti-di-interesse\/\" aria-label=\"Mehr Informationen \u00fcber Policy di gestione dei conflitti di interesse nella prestazione dei servizi e delle attivit\u00e0 di investimento\">Mehr erfahren<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_import_markdown_pro_load_document_selector":0,"_import_markdown_pro_submit_text_textarea":"","footnotes":""},"class_list":["post-6482","page","type-page","status-publish"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Policy di gestione dei conflitti di interesse nella prestazione dei servizi e delle attivit\u00e0 di investimento &#8226; Real Estate<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.realestate.it\/de\/policy-gestione-conflitti-di-interesse\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Policy di gestione dei conflitti di interesse nella prestazione dei servizi e delle attivit\u00e0 di investimento &#8226; Real Estate\" \/>\n<meta property=\"og:description\" content=\"Policy di gestione dei conflitti di interesse nella prestazione dei servizi e delle attivit\u00e0 di investimento ID documento: Policy conflitti di interesse Versione: 1.0 Data: 18\/12\/2019 Autore: Thomas Moroder Approvato da: Amministratori Riservatezza: Documento pubblico DEFINIZIONI Gestore: REAL ESTATE INFORMATION TECHNOLOGY Srl, in forma abbreviata REALESTATE.IT Srl sede legale ed amministrativa: Laion (BZ), S. Pietro ... Mehr erfahren\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.realestate.it\/de\/policy-gestione-conflitti-di-interesse\/\" \/>\n<meta property=\"og:site_name\" content=\"Real Estate\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/realestatecrowd\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.realestate.it\/wp-content\/uploads\/2019\/10\/patrick-tomasso-gMes5dNykus-unsplash-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1922\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@realestateit\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"15\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.realestate.it\\\/de\\\/policy-gestione-conflitti-di-interesse\\\/\",\"url\":\"https:\\\/\\\/www.realestate.it\\\/de\\\/policy-gestione-conflitti-di-interesse\\\/\",\"name\":\"Policy di gestione dei conflitti di interesse nella prestazione dei servizi e delle attivit\u00e0 di investimento &#8226; Real Estate\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.realestate.it\\\/de\\\/#website\"},\"datePublished\":\"2019-12-18T20:45:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.realestate.it\\\/de\\\/policy-gestione-conflitti-di-interesse\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.realestate.it\\\/de\\\/policy-gestione-conflitti-di-interesse\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.realestate.it\\\/de\\\/policy-gestione-conflitti-di-interesse\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.realestate.it\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Policy di gestione dei conflitti di interesse nella prestazione dei servizi e delle attivit\u00e0 di investimento\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.realestate.it\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.realestate.it\\\/de\\\/\",\"name\":\"Real Estate\",\"description\":\"Investire nell'immobiliare\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.realestate.it\\\/de\\\/#organization\"},\"alternateName\":\"RealEstate.IT\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.realestate.it\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.realestate.it\\\/de\\\/#organization\",\"name\":\"Real Estate Information Technologies Srl\",\"alternateName\":\"RealEstate.IT Srl\",\"url\":\"https:\\\/\\\/www.realestate.it\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.realestate.it\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.realestate.it\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-reit-jewel-big-darkgrey_BG_inverted.png\",\"contentUrl\":\"https:\\\/\\\/www.realestate.it\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-reit-jewel-big-darkgrey_BG_inverted.png\",\"width\":512,\"height\":512,\"caption\":\"Real Estate Information Technologies Srl\"},\"image\":{\"@id\":\"https:\\\/\\\/www.realestate.it\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/realestatecrowd\",\"https:\\\/\\\/x.com\\\/realestateit\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Policy di gestione dei conflitti di interesse nella prestazione dei servizi e delle attivit\u00e0 di investimento &#8226; Real Estate","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.realestate.it\/de\/policy-gestione-conflitti-di-interesse\/","og_locale":"de_DE","og_type":"article","og_title":"Policy di gestione dei conflitti di interesse nella prestazione dei servizi e delle attivit\u00e0 di investimento &#8226; Real Estate","og_description":"Policy di gestione dei conflitti di interesse nella prestazione dei servizi e delle attivit\u00e0 di investimento ID documento: Policy conflitti di interesse Versione: 1.0 Data: 18\/12\/2019 Autore: Thomas Moroder Approvato da: Amministratori Riservatezza: Documento pubblico DEFINIZIONI Gestore: REAL ESTATE INFORMATION TECHNOLOGY Srl, in forma abbreviata REALESTATE.IT Srl sede legale ed amministrativa: Laion (BZ), S. Pietro ... Mehr erfahren","og_url":"https:\/\/www.realestate.it\/de\/policy-gestione-conflitti-di-interesse\/","og_site_name":"Real Estate","article_publisher":"https:\/\/www.facebook.com\/realestatecrowd","og_image":[{"width":2560,"height":1922,"url":"https:\/\/www.realestate.it\/wp-content\/uploads\/2019\/10\/patrick-tomasso-gMes5dNykus-unsplash-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@realestateit","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"15\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.realestate.it\/de\/policy-gestione-conflitti-di-interesse\/","url":"https:\/\/www.realestate.it\/de\/policy-gestione-conflitti-di-interesse\/","name":"Policy di gestione dei conflitti di interesse nella prestazione dei servizi e delle attivit\u00e0 di investimento &#8226; Real Estate","isPartOf":{"@id":"https:\/\/www.realestate.it\/de\/#website"},"datePublished":"2019-12-18T20:45:47+00:00","breadcrumb":{"@id":"https:\/\/www.realestate.it\/de\/policy-gestione-conflitti-di-interesse\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.realestate.it\/de\/policy-gestione-conflitti-di-interesse\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.realestate.it\/de\/policy-gestione-conflitti-di-interesse\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.realestate.it\/de\/"},{"@type":"ListItem","position":2,"name":"Policy di gestione dei conflitti di interesse nella prestazione dei servizi e delle attivit\u00e0 di investimento"}]},{"@type":"WebSite","@id":"https:\/\/www.realestate.it\/de\/#website","url":"https:\/\/www.realestate.it\/de\/","name":"Real Estate","description":"Investire nell'immobiliare","publisher":{"@id":"https:\/\/www.realestate.it\/de\/#organization"},"alternateName":"RealEstate.IT","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.realestate.it\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.realestate.it\/de\/#organization","name":"Real Estate Information Technologies Srl","alternateName":"RealEstate.IT Srl","url":"https:\/\/www.realestate.it\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.realestate.it\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.realestate.it\/wp-content\/uploads\/2024\/05\/cropped-reit-jewel-big-darkgrey_BG_inverted.png","contentUrl":"https:\/\/www.realestate.it\/wp-content\/uploads\/2024\/05\/cropped-reit-jewel-big-darkgrey_BG_inverted.png","width":512,"height":512,"caption":"Real Estate Information Technologies Srl"},"image":{"@id":"https:\/\/www.realestate.it\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/realestatecrowd","https:\/\/x.com\/realestateit"]}]}},"_links":{"self":[{"href":"https:\/\/www.realestate.it\/de\/wp-json\/wp\/v2\/pages\/6482","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.realestate.it\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.realestate.it\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.realestate.it\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.realestate.it\/de\/wp-json\/wp\/v2\/comments?post=6482"}],"version-history":[{"count":0,"href":"https:\/\/www.realestate.it\/de\/wp-json\/wp\/v2\/pages\/6482\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.realestate.it\/de\/wp-json\/wp\/v2\/media?parent=6482"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}